{"id":3354,"date":"2024-02-14T14:09:39","date_gmt":"2024-02-14T13:09:39","guid":{"rendered":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361.jpeg"},"modified":"2024-02-14T14:09:39","modified_gmt":"2024-02-14T13:09:39","slug":"img_0361","status":"inherit","type":"attachment","link":"http:\/\/grundschule-cadenberge.de\/index.php\/2024\/02\/14\/spass-beim-faschingsfest-in-der-grundschule\/img_0361\/","title":{"rendered":"IMG_0361"},"author":7,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-scaled.jpeg'><img loading=\"lazy\" width=\"300\" height=\"225\" src=\"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-300x225.jpeg 300w, http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-1024x768.jpeg 1024w, http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-768x576.jpeg 768w, http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-1536x1152.jpeg 1536w, http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-2048x1536.jpeg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1920,"file":"IMG_0361-scaled.jpeg","filesize":769289,"sizes":{"medium":{"file":"IMG_0361-300x225.jpeg","width":300,"height":225,"filesize":32977,"mime_type":"image\/jpeg","source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-300x225.jpeg"},"large":{"file":"IMG_0361-1024x768.jpeg","width":1024,"height":768,"filesize":126009,"mime_type":"image\/jpeg","source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-1024x768.jpeg"},"thumbnail":{"file":"IMG_0361-150x150.jpeg","width":150,"height":150,"filesize":24550,"mime_type":"image\/jpeg","source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-150x150.jpeg"},"medium_large":{"file":"IMG_0361-768x576.jpeg","width":768,"height":576,"filesize":84394,"mime_type":"image\/jpeg","source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-768x576.jpeg"},"1536x1536":{"file":"IMG_0361-1536x1152.jpeg","width":1536,"height":1152,"filesize":254922,"mime_type":"image\/jpeg","source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-1536x1152.jpeg"},"2048x2048":{"file":"IMG_0361-2048x1536.jpeg","width":2048,"height":1536,"filesize":469485,"mime_type":"image\/jpeg","source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-2048x1536.jpeg"},"optimizer_thumb":{"file":"IMG_0361-400x270.jpeg","width":400,"height":270,"filesize":38522,"mime_type":"image\/jpeg","source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-400x270.jpeg"},"full":{"file":"IMG_0361-scaled.jpeg","width":2560,"height":1920,"mime_type":"image\/jpeg","source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-scaled.jpeg"}},"image_meta":{"aperture":"2.4","credit":"","camera":"iPad (8th generation)","caption":"","created_timestamp":"1707819624","copyright":"","focal_length":"3.3","iso":"320","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"original_image":"IMG_0361.jpeg"},"post":3346,"source_url":"http:\/\/grundschule-cadenberge.de\/wp-content\/uploads\/IMG_0361-scaled.jpeg","_links":{"self":[{"href":"http:\/\/grundschule-cadenberge.de\/index.php\/wp-json\/wp\/v2\/media\/3354"}],"collection":[{"href":"http:\/\/grundschule-cadenberge.de\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/grundschule-cadenberge.de\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/grundschule-cadenberge.de\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"http:\/\/grundschule-cadenberge.de\/index.php\/wp-json\/wp\/v2\/comments?post=3354"}]}}